{"id":397056,"date":"2020-10-27T10:56:11","date_gmt":"2020-10-27T14:56:11","guid":{"rendered":"https:\/\/patientworthy.wpengine.com\/2020\/10\/27\/nuevo-inhalante-es-un-tratamiento-potencial-para-la-fibrosis-quistica\/"},"modified":"2020-10-27T10:56:24","modified_gmt":"2020-10-27T14:56:24","slug":"nuevo-inhalante-es-un-tratamiento-potencial-para-la-fibrosis-quistica","status":"publish","type":"post","link":"https:\/\/patientworthy.com\/es\/2020\/10\/27\/nuevo-inhalante-es-un-tratamiento-potencial-para-la-fibrosis-quistica\/","title":{"rendered":"Nuevo Inhalante es un Tratamiento Potencial para la Fibrosis Qu\u00edstica"},"content":{"rendered":"<p>Ionis Pharmaceuticals ha publicado recientemente los datos de su ensayo cl\u00ednico de IONIS-ENAC-2.5<sub>Rx<\/sub>, un tratamiento para la fibrosis qu\u00edstica. <a href=\"https:\/\/www.prnewswire.com\/news-releases\/ionis-inhaled-antisense-medicine-demonstrates-potential-as-a-novel-treatment-for-cystic-fibrosis-301150622.html\">Seg\u00fan Newswire<\/a>, el estudio mostr\u00f3 resultados muy positivos, y los voluntarios sanos vieron una disminuci\u00f3n significativa en la expresi\u00f3n del canal de sodio epitelial.<\/p>\n<h2>Sobre la Fibrosis Qu\u00edstica<\/h2>\n<p><a href=\"https:\/\/patientworthy.com\/cystic-fibrosis-cf\/\">La fibrosis qu\u00edstica<\/a> es un trastorno gen\u00e9tico que se caracteriza por un da\u00f1o progresivo en los sistemas respiratorio y digestivo. Las personas con fibrosis qu\u00edstica no tienen el moco resbaladizo que normalmente se encuentra en los pulmones. En cambio, tienen un moco espeso y pegajoso que se acumula en su sistema. Esta acumulaci\u00f3n provoca obstrucciones en las v\u00edas respiratorias, que luego atrapa las bacterias y causa problemas respiratorios, infecciones, da\u00f1o pulmonar e insuficiencia respiratoria. Tambi\u00e9n puede bloquear las enzimas digestivas, lo que dificulta la absorci\u00f3n de nutrientes. La fibrosis qu\u00edstica es un trastorno recesivo, lo que significa que el gen mutado debe ser transmitido por ambos padres. El gen responsable de esta afecci\u00f3n afecta la prote\u00edna que regula el movimiento de la sal. La mutaci\u00f3n en el gen tambi\u00e9n var\u00eda en severidad.<\/p>\n<p>Los s\u00edntomas de la fibrosis qu\u00edstica afectan los sistemas respiratorio y digestivo. Incluyen tos y sibilancias persistentes, dificultad para respirar, dificultad para hacer ejercicio, infecciones pulmonares frecuentes, congesti\u00f3n nasal, problemas para aumentar de peso, estre\u00f1imiento, infertilidad masculina, piel con sabor salado e intolerancia al ejercicio.<\/p>\n<h2>Acerca de IONIS-ENAC-2.5<sub>Rx<\/sub> y el estudio<\/h2>\n<p>IONIS-ENAC-2.5<sub>Rx<\/sub> es un medicamento antisentido que est\u00e1 destinado a reducir la expresi\u00f3n del canal de sodio epitelial (ENaC) en los pulmones. Como este canal es hiperactivo en las personas con fibrosis qu\u00edstica, los investigadores esperan que este tratamiento reduzca los s\u00edntomas.<\/p>\n<p>Se evalu\u00f3 en un estudio de escalada de dosis \u00fanica en el que el criterio de valoraci\u00f3n principal era evaluar la farmacocin\u00e9tica y la seguridad. Se inscribieron 32 participantes y recibieron 3, 10, 37.5 o 100 mg de IONIS-ENAC-2.5<sub>Rx<\/sub> a trav\u00e9s de un nebulizador de malla Pari eFlow una vez a la semana. Durante las siguientes 13 semanas, los investigadores siguieron a los participantes. Para evaluar el resultado final, se les realiz\u00f3 una fibrobroncoscopia.<\/p>\n<p>Los investigadores encontraron que hubo una disminuci\u00f3n media en la expresi\u00f3n de ENaC del 55.6%. Este resultado es muy positivo, y los profesionales m\u00e9dicos y los pacientes est\u00e1n emocionados de ver c\u00f3mo avanza el desarrollo de este tratamiento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ionis Pharmaceuticals ha publicado recientemente los datos de su ensayo cl\u00ednico de IONIS-ENAC-2.5Rx, un tratamiento para la fibrosis qu\u00edstica. Seg\u00fan Newswire, el estudio mostr\u00f3 resultados muy positivos, y los voluntarios sanos vieron una disminuci\u00f3n significativa en la expresi\u00f3n del canal de sodio epitelial. Sobre la Fibrosis Qu\u00edstica La fibrosis qu\u00edstica es un trastorno gen\u00e9tico que [&hellip;]<\/p>\n","protected":false},"author":1025,"featured_media":397057,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[12179],"tags":[13172,12181,12109,14397,14398],"_links":{"self":[{"href":"https:\/\/patientworthy.com\/es\/wp-json\/wp\/v2\/posts\/397056"}],"collection":[{"href":"https:\/\/patientworthy.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/patientworthy.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/patientworthy.com\/es\/wp-json\/wp\/v2\/users\/1025"}],"replies":[{"embeddable":true,"href":"https:\/\/patientworthy.com\/es\/wp-json\/wp\/v2\/comments?post=397056"}],"version-history":[{"count":0,"href":"https:\/\/patientworthy.com\/es\/wp-json\/wp\/v2\/posts\/397056\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/patientworthy.com\/es\/wp-json\/wp\/v2\/media\/397057"}],"wp:attachment":[{"href":"https:\/\/patientworthy.com\/es\/wp-json\/wp\/v2\/media?parent=397056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/patientworthy.com\/es\/wp-json\/wp\/v2\/categories?post=397056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/patientworthy.com\/es\/wp-json\/wp\/v2\/tags?post=397056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}