{"id":422175,"date":"2020-11-05T11:01:17","date_gmt":"2020-11-05T16:01:17","guid":{"rendered":"https:\/\/patientworthy.wpengine.com\/2020\/11\/05\/no-hay-relacion-entre-la-vacuna-contra-el-virus-del-papiloma-humano-y-los-sindromes-de-disfuncion-autonoma\/"},"modified":"2020-11-05T11:01:26","modified_gmt":"2020-11-05T16:01:26","slug":"no-hay-relacion-entre-la-vacuna-contra-el-virus-del-papiloma-humano-y-los-sindromes-de-disfuncion-autonoma","status":"publish","type":"post","link":"https:\/\/patientworthy.com\/es\/2020\/11\/05\/no-hay-relacion-entre-la-vacuna-contra-el-virus-del-papiloma-humano-y-los-sindromes-de-disfuncion-autonoma\/","title":{"rendered":"No Hay Relaci\u00f3n Entre la Vacuna Contra el Virus del Papiloma Humano y los S\u00edndromes de Disfunci\u00f3n Aut\u00f3noma"},"content":{"rendered":"<p><em>por Lauren Taylor de <a href=\"http:\/\/inthecloudcopy.com\" target=\"_blank\" rel=\"noopener noreferrer\">In The Cloud Copy<\/a><\/em><\/p>\n<p><strong>La vacuna contra el virus del papiloma humano (VPH) se ha estado administrando a adolescentes y adultos j\u00f3venes en todo el mundo durante m\u00e1s de una d\u00e9cada.<\/strong> Ha tenido un gran \u00e9xito, como se dice, para prevenir algunos c\u00e1nceres, pero algunos padres y pacientes dudan en recibir la vacuna, ya que temen la posibilidad de efectos secundarios. En particular, ha habido rumores de v\u00ednculos entre la vacuna contra el VPH y s\u00edndromes de disfunci\u00f3n aut\u00f3noma como<a href=\"https:\/\/patientworthy.com\/postural-orthostatic-tachycardia-syndrome-pots\/\" target=\"_blank\" rel=\"noopener noreferrer\">el s\u00edndrome de taquicardia ortost\u00e1tica postural<\/a>, <a href=\"https:\/\/patientworthy.com\/myalgic-encephalomyelitis-or-chronic-fatigue-syndrome-me-or-cfs\/\" target=\"_blank\" rel=\"noopener noreferrer\">el s\u00edndrome de fatiga cr\u00f3nica<\/a> <a href=\"https:\/\/patientworthy.com\/complex-regional-pain-syndrome-crps\/\" target=\"_blank\" rel=\"noopener noreferrer\">y el s\u00edndrome de dolor regional complejo<\/a>.<\/p>\n<p>Se realiz\u00f3 un estudio en Dinamarca para evaluar si exist\u00eda alguna validez en las afirmaciones de un v\u00ednculo entre la vacunaci\u00f3n y cualquiera de las afecciones mencionadas anteriormente. Se eligi\u00f3 Dinamarca como lugar de estudio debido a que sus registros nacionales dan f\u00e1cil acceso a quienes han sido vacunados y no.<\/p>\n<h2>M\u00e9todos de Estudio<\/h2>\n<p>Se desarroll\u00f3 una cohorte de estudio que inclu\u00eda a todas las participantes femeninas que nacieron en Dinamarca y ten\u00edan entre 10 y 44 a\u00f1os de edad en el per\u00edodo de tiempo de 2007 a 2016. Tambi\u00e9n se incluy\u00f3 el estado de la vacuna contra el VPH, as\u00ed como el diagn\u00f3stico o posible diagn\u00f3stico de s\u00edndrome de dolor regional complejo, s\u00edndrome de taquicardia ortost\u00e1tica postural y s\u00edndrome de fatiga cr\u00f3nica. Este estudio se realiz\u00f3 finalmente debido a la preocupaci\u00f3n del p\u00fablico sobre la seguridad de esta vacuna.<\/p>\n<h2>Resultados del Estudio<\/h2>\n<p>El estudio encontr\u00f3 que 529,547 mujeres recibieron al menos una dosis \u00fanica de la vacuna tetravalente contra el VPH. La mediana de edad a la que se administr\u00f3 la vacuna fue de 12.6 a\u00f1os para las ni\u00f1as de entre 10 y 17 a\u00f1os y de 24.3 a\u00f1os para las mujeres de entre 18 y 44 a\u00f1os. Los tres s\u00edndromes mencionados se observaron en 869 de los participantes del estudio, lo que equivale a una tasa de incidencia de 8.21 por 100,000 personas. El s\u00edndrome m\u00e1s com\u00fanmente visto fue el s\u00edndrome de dolor regional complejo, con 535 participantes informando, seguido de 198 participantes con s\u00edndrome de taquicardia ortost\u00e1tica postural y s\u00edndrome de fatiga cr\u00f3nica que afecta a 136.<\/p>\n<p>Se observ\u00f3 un aumento en las tasas de incidencia para todos los s\u00edndromes durante el per\u00edodo de estudio y fue especialmente prominente para el s\u00edndrome de taquicardia ortost\u00e1tica postural. Todos los s\u00edndromes vieron las tasas de incidencia m\u00e1s altas en ni\u00f1as que se encuentran en el rango de edad de la adolescencia. Mientras que la incidencia del s\u00edndrome de taquicardia ortost\u00e1tica postural disminuy\u00f3 considerablemente con la edad, los otros dos s\u00edndromes mostraron un aumento marginal con la edad. En las ni\u00f1as de 10 a 17 a\u00f1os, la mediana de edad a la que se realiz\u00f3 el diagn\u00f3stico fue de 14 a\u00f1os, mientras que la mediana de edad al diagn\u00f3stico fue de 33.3 a\u00f1os en el rango de edad de 18 a 44 a\u00f1os.<\/p>\n<h2>Conclusiones<\/h2>\n<p>No parece que exista una asociaci\u00f3n notable entre la vacunaci\u00f3n tetravalente contra el virus del papiloma humano y las tasas de diagn\u00f3stico de s\u00edndrome de taquicardia ortost\u00e1tica, s\u00edndrome de dolor regional complejo y s\u00edndrome de fatiga cr\u00f3nica. Otros estudios de este tipo se han realizado analizando cualquier asociaci\u00f3n entre la vacunaci\u00f3n contra el VPH y los s\u00edndromes con disfunci\u00f3n auton\u00f3mica. Los estudios en Finlandia, el Reino Unido y Noruega no han encontrado asociaci\u00f3n entre la vacunaci\u00f3n y estos s\u00edndromes. Despu\u00e9s de revisar los resultados del estudio, los investigadores concluyeron que la vacuna tetravalente contra el virus del papiloma humano es segura para las ni\u00f1as adolescentes, as\u00ed como para la poblaci\u00f3n adulta femenina que puede necesitar una vacuna de actualizaci\u00f3n. Si bien todos los estudios son limitados, el poder estad\u00edstico de este estudio les da a los investigadores confianza al decir que existe un riesgo poco probable entre la vacunaci\u00f3n y el desarrollo de cualquiera de los s\u00edndromes mencionados anteriormente.<\/p>\n<p>Obtenga m\u00e1s informaci\u00f3n sobre este estudio <a href=\"https:\/\/www.contagionlive.com\/view\/hpv-vaccination-does-not-increase-risk-of-syndromes-with-autonomic-dysfunction\" target=\"_blank\" rel=\"noopener noreferrer\">aqu\u00ed<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>por Lauren Taylor de In The Cloud Copy La vacuna contra el virus del papiloma humano (VPH) se ha estado administrando a adolescentes y adultos j\u00f3venes en todo el mundo durante m\u00e1s de una d\u00e9cada. Ha tenido un gran \u00e9xito, como se dice, para prevenir algunos c\u00e1nceres, pero algunos padres y pacientes dudan en recibir [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":376004,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[12815,12398,16419],"tags":[12816,16481,16420,19680,19681],"_links":{"self":[{"href":"https:\/\/patientworthy.com\/es\/wp-json\/wp\/v2\/posts\/422175"}],"collection":[{"href":"https:\/\/patientworthy.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/patientworthy.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/patientworthy.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/patientworthy.com\/es\/wp-json\/wp\/v2\/comments?post=422175"}],"version-history":[{"count":0,"href":"https:\/\/patientworthy.com\/es\/wp-json\/wp\/v2\/posts\/422175\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/patientworthy.com\/es\/wp-json\/wp\/v2\/media\/376004"}],"wp:attachment":[{"href":"https:\/\/patientworthy.com\/es\/wp-json\/wp\/v2\/media?parent=422175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/patientworthy.com\/es\/wp-json\/wp\/v2\/categories?post=422175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/patientworthy.com\/es\/wp-json\/wp\/v2\/tags?post=422175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}