{"id":190830,"date":"2020-06-14T19:46:27","date_gmt":"2020-06-14T23:46:27","guid":{"rendered":"https:\/\/patientworthy.wpengine.com\/?p=190830&#038;preview=true&#038;preview_id=190830"},"modified":"2020-06-23T11:50:05","modified_gmt":"2020-06-23T15:50:05","slug":"lanalyse-du-langage-expressif-peut-provoquer-la-creation-de-nouvelles-options-de-traitement-contre-le-syndrome-de-lx-fragile","status":"publish","type":"post","link":"https:\/\/patientworthy.com\/fr\/2020\/06\/14\/lanalyse-du-langage-expressif-peut-provoquer-la-creation-de-nouvelles-options-de-traitement-contre-le-syndrome-de-lx-fragile\/","title":{"rendered":"L\u2019Analyse du langage expressif peut provoquer la cr\u00e9ation de nouvelles options de traitement contre le syndrome de l\u2019X fragile"},"content":{"rendered":"<p><em>Par Danielle Bradshaw du site <a href=\"http:\/\/inthecloudcopy.com\/\">In The Cloud Copy<\/a><\/em><\/p>\n<p>L&rsquo;analyse du langage expressif, ou ELS (pour l\u2019anglais, <em>expressive language sampling<\/em>), pourrait potentiellement aider les chercheurs \u00e0 mieux mesurer l&rsquo;efficacit\u00e9 des traitements pour les patients atteints du syndrome de l\u2019X fragile ou d&rsquo;autres d\u00e9ficiences intellectuelles. Au fil du temps, de plus en plus de compr\u00e9hension et de connaissances ont \u00e9t\u00e9 acquises concernant le fonctionnement de la d\u00e9ficience intellectuelle et, par cons\u00e9quent, les traitements peuvent d\u00e9sormais \u00eatre adapt\u00e9s \u00e0 des troubles sp\u00e9cifiques.<\/p>\n<p>V\u00e9rifier que ces traitements fonctionnent bien &#8211; les tester &#8211; n\u00e9cessite des essais cliniques m\u00e9ticuleusement organis\u00e9s. Les tests pour les traitements du syndrome de l&rsquo;X fragile ont cependant laiss\u00e9 beaucoup \u00e0 d\u00e9sirer dans le pass\u00e9, car plus de 24 ont \u00e9t\u00e9 test\u00e9s et ils se sont r\u00e9v\u00e9l\u00e9s pour la plupart inefficaces.<\/p>\n<h2>Qu\u2019est-ce que c\u2019est que le syndrome de l\u2019X fragile\u00a0?<\/h2>\n<p>Les personnes atteintes du <a href=\"https:\/\/patientworthy.com\/fragile-x-syndrome\/\">syndrome de l&rsquo;X fragile<\/a> peuvent souffrir de divers troubles du d\u00e9veloppement et d&rsquo;apprentissage ainsi que de certains troubles cognitifs. C\u2019est une maladie g\u00e9n\u00e9tique qui appara\u00eet principalement chez les hommes, mais elle peut aussi se pr\u00e9senter chez les femmes. Le syndrome de l\u2019X fragile peut \u00e9galement entra\u00eener de l&rsquo;anxi\u00e9t\u00e9, un trouble d\u00e9ficitaire de l&rsquo;attention (TDA) et divers s\u00e9v\u00e9rit\u00e9s d&rsquo;autisme, selon la personne en question.<\/p>\n<h2>Comment la ELS a \u00e9t\u00e9 choisie comme une unit\u00e9 de mesure efficace pour les traitements<\/h2>\n<p>Comme indiqu\u00e9, d&rsquo;autres m\u00e9thodes utilis\u00e9es pour analyser le traitement ont donn\u00e9 des r\u00e9sultats plut\u00f4t m\u00e9diocres. Une des principales raisons que cela se produit est \u00e0 cause de l&rsquo;effet d&rsquo;entra\u00eenement. Fondamentalement, c&rsquo;est \u00ab la pratique m\u00e8ne \u00e0 la perfection \u00bb ; plus les participants participent \u00e0 un essai, plus ils obtiennent de mieux r\u00e9sultats car ils ont pass\u00e9 les tests tant de fois. Il est donc difficile de d\u00e9terminer si le traitement fonctionne r\u00e9ellement ou si le r\u00e9sultat provient simplement de tests r\u00e9p\u00e9t\u00e9s.<\/p>\n<p>La ELS s&rsquo;est av\u00e9r\u00e9e \u00eatre un moyen de surmonter l\u2019effet d\u2019entra\u00eenement. Parce que l&rsquo;efficacit\u00e9 linguistique peut \u00eatre li\u00e9e \u00e0 des d\u00e9ficiences intellectuelles, la ELS est un outil utile pour cr\u00e9er des mesures d&rsquo;effet.<\/p>\n<h2>Comment fonctionne la ELS<\/h2>\n<p>La ELS a deux parties ; dont le premier est la conversation. Dans cette partie (qui durait en moyenne environ 12 minutes pour cette \u00e9tude), l&rsquo;administrateur du test parle au participant de quelque chose qu&rsquo;il aime \u2013 des passe-temps, des personnes qu&rsquo;il aime, de leurs films pr\u00e9f\u00e9r\u00e9s &#8211; puis passe \u00e0 un sujet pr\u00e9d\u00e9fini. L&rsquo;administrateur suit ensuite un texte qui a \u00e9t\u00e9 \u00e9crit de mani\u00e8re \u00e0 permettre au patient de mener la conversation.<\/p>\n<p>Dans la deuxi\u00e8me partie de l&rsquo;examen, la partie \u00ab narration \u00bb, l&rsquo;examinateur montre au patient un livre d&rsquo;images. Le patient a la possibilit\u00e9 de raconter sa version de l&rsquo;histoire du livre dans ses propres mots en environ 10 \u00e0 15 minutes avec une participation limit\u00e9e du chercheur.<\/p>\n<p>Chaque partie du test est contr\u00f4l\u00e9e par :<\/p>\n<ul>\n<li>La loquacit\u00e9 de chaque participant<\/li>\n<li>Si les mots parl\u00e9s sont facilement compris<\/li>\n<li>Le vocabulaire du patient<\/li>\n<li>La complexit\u00e9 de la structure et de la formation des mots et des phrases du patient<\/li>\n<\/ul>\n<h2>L\u2019\u00c9tude et les r\u00e9sultats<\/h2>\n<p>106 participants \u00e2g\u00e9s de 6 ans \u00e0 23 ans ont \u00e9t\u00e9 \u00e9valu\u00e9s deux fois, la deuxi\u00e8me analyse ayant lieu un mois apr\u00e8s la premi\u00e8re. La majorit\u00e9 des patients &#8211; 85 au total &#8211; \u00e9taient des hommes. Tous poss\u00e9daient un QI de 70 ou moins et communiquaient principalement par la parole. Le nombre de patients qui ne pouvaient pas ou ne voulaient pas participer \u00e0 l&rsquo;analyse ELS \u00e9tait moins de 15% (environ 15 patients) et se composait principalement de ceux qui avaient un QI plus faible, avaient des signes d&rsquo;autisme plus apparents ou faisaient partie des plus jeunes participants.<\/p>\n<p>Il n&rsquo;y avait pas de grande diff\u00e9rence entre les deux analyses, ce qui semble indiquer que l&rsquo;effet d&rsquo;entra\u00eenement n&rsquo;\u00e9tait pas un probl\u00e8me. Si tel \u00e9tait le cas, les r\u00e9sultats du deuxi\u00e8me test seraient meilleurs. Les r\u00e9sultats de l\u2019analyse ELS ont \u00e9galement \u00e9t\u00e9 compar\u00e9s avec les r\u00e9sultats obtenus par des questionnaires standardis\u00e9s. Les r\u00e9sultats de la ELS pour le vocabulaire, la structure des mots et des phrases et la facilit\u00e9 de compr\u00e9hension s&rsquo;accordent assez bien avec les r\u00e9sultats du questionnaire. Mais ce n\u2019\u00e9tait pas le cas pour le manque de fluidit\u00e9 et pour la loquacit\u00e9.<\/p>\n<p>L&rsquo;absence de rapport dans les deux derni\u00e8res cat\u00e9gories est encore inconnue et l&rsquo;utilisation de la loquacit\u00e9 et du manque de fluidit\u00e9 comme mesures d&rsquo;effet est d\u00e9conseill\u00e9e. Dans l&rsquo;ensemble, l&rsquo;\u00e9tude a montr\u00e9 que la ELS peut \u00eatre utilis\u00e9e comme mesure efficace pour les traitements contre le syndrome de l&rsquo;X fragile et d&rsquo;autres handicaps similaires.<\/p>\n<p>Pour lire l&rsquo;article originale, cliquez<a href=\"https:\/\/fragilexnewstoday.com\/2020\/04\/28\/study-supports-expressive-language-sampling-for-fragile-x-research\/\"> ici.<\/a><\/p>\n<hr \/>\n<h4 class=\"p1\" style=\"text-align: center;\">C\u2019est notre meilleur essaie pour traduire des infos sur les maladies rares dans votre langue. Nous savons qu\u2019il est possible que cette traduction ne saisisse pas avec pr\u00e9cision toutes les nuances de votre langue maternelle, donc si vous avez des corrections ou des suggestions, veuillez nous les envoyer \u00e0 l\u2019adresse suivante : <a href=\"mailto:contribute@patientworthy.com\"><span class=\"s1\">contribute@patientworthy.com<\/span><\/a>.<\/h4>\n","protected":false},"excerpt":{"rendered":"<p>Par Danielle Bradshaw du site In The Cloud Copy L&rsquo;analyse du langage expressif, ou ELS (pour l\u2019anglais, expressive language sampling), pourrait potentiellement aider les chercheurs \u00e0 mieux mesurer l&rsquo;efficacit\u00e9 des traitements pour les patients atteints du syndrome de l\u2019X fragile ou d&rsquo;autres d\u00e9ficiences intellectuelles. Au fil du temps, de plus en plus de compr\u00e9hension et [&hellip;]<\/p>\n","protected":false},"author":904,"featured_media":189648,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[13986],"tags":[14003,14042,14792],"_links":{"self":[{"href":"https:\/\/patientworthy.com\/fr\/wp-json\/wp\/v2\/posts\/190830"}],"collection":[{"href":"https:\/\/patientworthy.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/patientworthy.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/patientworthy.com\/fr\/wp-json\/wp\/v2\/users\/904"}],"replies":[{"embeddable":true,"href":"https:\/\/patientworthy.com\/fr\/wp-json\/wp\/v2\/comments?post=190830"}],"version-history":[{"count":0,"href":"https:\/\/patientworthy.com\/fr\/wp-json\/wp\/v2\/posts\/190830\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/patientworthy.com\/fr\/wp-json\/wp\/v2\/media\/189648"}],"wp:attachment":[{"href":"https:\/\/patientworthy.com\/fr\/wp-json\/wp\/v2\/media?parent=190830"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/patientworthy.com\/fr\/wp-json\/wp\/v2\/categories?post=190830"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/patientworthy.com\/fr\/wp-json\/wp\/v2\/tags?post=190830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}